{"id":100276,"date":"2023-11-15T06:00:00","date_gmt":"2023-11-15T05:00:00","guid":{"rendered":"https:\/\/metacomp.wpenginepowered.com\/info-hub\/sin-categoria\/metacompliances-dach-expansion-gains-momentum-with-iys-acquisition\/"},"modified":"2025-09-22T02:11:58","modified_gmt":"2025-09-22T01:11:58","slug":"la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys","status":"publish","type":"post","link":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys","title":{"rendered":"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS"},"content":{"rendered":"&#13;\n<p><strong>15 de noviembre de 2023: <\/strong><a href=\"https:\/\/www.metacompliance.com\/\">MetaCompliance<\/a>, la empresa l\u00edder en Europa en formaci\u00f3n sobre concienciaci\u00f3n en ciberseguridad, se enorgullece de anunciar la adquisici\u00f3n de Increase Your Skills GmbH (IYS), la empresa de formaci\u00f3n sobre concienciaci\u00f3n en ciberseguridad de r\u00e1pido crecimiento con sede en Leipzig, Alemania.<\/p>&#13;\n&#13;\n<p>Esta adquisici\u00f3n estrat\u00e9gica no s\u00f3lo refuerza la posici\u00f3n de MetaCompliance en el mercado clave alem\u00e1n, sino que tambi\u00e9n subraya el compromiso de la empresa de aprovechar el inmenso potencial de r\u00e1pida expansi\u00f3n. Aprovechando su importante cuota de mercado y su visi\u00f3n visionaria, MetaCompliance pretende acelerar su crecimiento y consolidar su posici\u00f3n como la mayor plataforma de concienciaci\u00f3n en ciberseguridad de Europa. <\/p>&#13;\n&#13;\n<p>IYS destaca como actor clave en el panorama alem\u00e1n de la ciberseguridad, ofreciendo un espectro de soluciones expertas adaptadas al sector p\u00fablico y siendo pionera en tecnolog\u00eda de simulaci\u00f3n de phishing basada en IA. La adquisici\u00f3n introduce adem\u00e1s un s\u00f3lido equipo directivo que est\u00e1 preparado para encabezar un r\u00e1pido crecimiento en la regi\u00f3n DACH. <\/p>&#13;\n&#13;\n<p>El director general de MetaCompliance, James Mackay, coment\u00f3: <em>\u00abIYS ha demostrado un crecimiento notable, respaldado por un compromiso inquebrantable con la orientaci\u00f3n al cliente y la innovaci\u00f3n incesante de sus productos. Resuena perfectamente con nuestros valores fundamentales y nuestra misi\u00f3n compartida de personalizar la formaci\u00f3n en ciberseguridad. Estamos encantados de integrar su excepcional equipo y su experiencia local, y esperamos poder ofrecer soluciones a\u00fan m\u00e1s avanzadas en toda la regi\u00f3n.\u00bb<\/em><\/p>&#13;\n&#13;\n<p>El cofundador de IYS, Hannes Hartung, a\u00f1adi\u00f3: <em>\u00abFormar parte de MetaCompliance marca un cap\u00edtulo apasionante para nosotros. La profundidad y amplitud del contenido de MetaCompliance, sus capacidades multiling\u00fces y su destreza operativa nos permitir\u00e1n proporcionar a nuestros clientes una oferta de productos y servicios enormemente enriquecida. Carolin y yo estamos encantados de unir fuerzas con el equipo mientras abrazamos con entusiasmo la oportunidad de liderar nuestros ambiciosos planes de crecimiento en la regi\u00f3n DACH.\u00bb<\/em><\/p>&#13;\n&#13;\n<p>  La cofundadora de IYS, Carolin Andree, a\u00f1adi\u00f3<em>: \u00abEstamos encantados de unirnos al equipo y esperamos encabezar nuestros ambiciosos planes de crecimiento en la regi\u00f3n DACH. Creemos que esta colaboraci\u00f3n ofrece una gran oportunidad tanto para el mercado DACH como para nosotros.\u00bb<\/em><\/p>&#13;\n&#13;\n<p>MetaCompliance complet\u00f3 la adquisici\u00f3n de IYS el<sup>3 de<\/sup> noviembre con el apoyo y la asistencia de Tenzing - el inversor tecnol\u00f3gico europeo de capital privado con sede en Londres, Reino Unido.<\/p>&#13;\n&#13;\n<p>ENDS<\/p>&#13;\n&#13;\n<p><strong>Notas para los editores:<\/strong><\/p>&#13;\n&#13;\n<p><a href=\"https:\/\/www.dropbox.com\/scl\/fi\/o7te92l0hch8w0tyjjple\/James-Mackay-MetaCompliance-CEO.jpg?rlkey=z7tm36sr1m3yet3eoxut4g539&amp;dl=0\">Aqu\u00ed puede descargarse<\/a> una foto de James Mackay, Director General de MetaCompliance.<\/p>&#13;\n&#13;\n<p><strong>Acerca de MetaCompliance:<\/strong><\/p>&#13;\n&#13;\n<p>MetaCompliance es un proveedor l\u00edder de soluciones de cumplimiento y ciberseguridad, dedicado a ayudar a las organizaciones a salvaguardar sus datos y promover una cultura de concienciaci\u00f3n sobre la seguridad. Con un fuerte enfoque en la concienciaci\u00f3n de seguridad personalizada, MetaCompliance capacita a las organizaciones para protegerse contra las amenazas de seguridad y los riesgos de cumplimiento.   <a href=\"https:\/\/www.metacompliance.com\/\">https:\/\/www.metacompliance.com\/<\/a><\/p>&#13;\n&#13;\n<p>-<\/p>&#13;\n&#13;\n<p><strong>Contacto de prensa<\/strong>:<\/p>&#13;\n&#13;\n<p>Peppa Sheridan, Peptalk Communications Ltd.<\/p>&#13;\n&#13;\n<p>T: +44 (0) 1787 323772 \/ M: +44 (0) 7725 121189 <a href=\"mailto:peppa@peptalkpr.co.uk\">peppa@peptalkpr.co.uk<\/a><\/p>&#13;\n","protected":false},"excerpt":{"rendered":"<p>&#13; 15 de noviembre de 2023: MetaCompliance, la empresa l\u00edder en Europa en formaci\u00f3n sobre concienciaci\u00f3n en ciberseguridad, se enorgullece de anunciar la adquisici\u00f3n de Increase Your Skills GmbH (IYS), &hellip; <a href=\"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys\">Contin\u00faa<\/a><\/p>\n","protected":false},"author":1,"featured_media":84649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"footnotes":""},"categories":[169],"class_list":["post-100276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS - MetaCompliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS - MetaCompliance\" \/>\n<meta property=\"og:description\" content=\"&#013; 15 de noviembre de 2023: MetaCompliance, la empresa l\u00edder en Europa en formaci\u00f3n sobre concienciaci\u00f3n en ciberseguridad, se enorgullece de anunciar la adquisici\u00f3n de Increase Your Skills GmbH (IYS), &hellip; Contin\u00faa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys\" \/>\n<meta property=\"og:site_name\" content=\"MetaCompliance\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-15T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T01:11:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"885\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rouge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rouge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys\"},\"author\":{\"name\":\"Rouge\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es#\\\/schema\\\/person\\\/fe1b1dd873af281510fb0ad5f3fb5b38\"},\"headline\":\"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS\",\"datePublished\":\"2023-11-15T05:00:00+00:00\",\"dateModified\":\"2025-09-22T01:11:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys\"},\"wordCount\":532,\"image\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metacompliance.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg\",\"articleSection\":[\"Noticias de la empresa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys\",\"url\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys\",\"name\":\"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS - MetaCompliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metacompliance.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg\",\"datePublished\":\"2023-11-15T05:00:00+00:00\",\"dateModified\":\"2025-09-22T01:11:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es#\\\/schema\\\/person\\\/fe1b1dd873af281510fb0ad5f3fb5b38\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#primaryimage\",\"url\":\"https:\\\/\\\/www.metacompliance.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg\",\"contentUrl\":\"https:\\\/\\\/www.metacompliance.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg\",\"width\":885,\"height\":560,\"caption\":\"MetaCumplimiento\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es\\\/noticias\\\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.metacompliance.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es#website\",\"url\":\"https:\\\/\\\/www.metacompliance.com\\\/es\",\"name\":\"MetaCompliance\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metacompliance.com\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/es#\\\/schema\\\/person\\\/fe1b1dd873af281510fb0ad5f3fb5b38\",\"name\":\"Rouge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g\",\"caption\":\"Rouge\"},\"sameAs\":[\"https:\\\/\\\/www.metacompliance.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS - MetaCompliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys","og_locale":"es_ES","og_type":"article","og_title":"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS - MetaCompliance","og_description":"&#13; 15 de noviembre de 2023: MetaCompliance, la empresa l\u00edder en Europa en formaci\u00f3n sobre concienciaci\u00f3n en ciberseguridad, se enorgullece de anunciar la adquisici\u00f3n de Increase Your Skills GmbH (IYS), &hellip; Contin\u00faa","og_url":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys","og_site_name":"MetaCompliance","article_published_time":"2023-11-15T05:00:00+00:00","article_modified_time":"2025-09-22T01:11:58+00:00","og_image":[{"width":885,"height":560,"url":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg","type":"image\/jpeg"}],"author":"Rouge","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rouge","Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#article","isPartOf":{"@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys"},"author":{"name":"Rouge","@id":"https:\/\/www.metacompliance.com\/es#\/schema\/person\/fe1b1dd873af281510fb0ad5f3fb5b38"},"headline":"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS","datePublished":"2023-11-15T05:00:00+00:00","dateModified":"2025-09-22T01:11:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys"},"wordCount":532,"image":{"@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#primaryimage"},"thumbnailUrl":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg","articleSection":["Noticias de la empresa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys","url":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys","name":"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS - MetaCompliance","isPartOf":{"@id":"https:\/\/www.metacompliance.com\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#primaryimage"},"image":{"@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#primaryimage"},"thumbnailUrl":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg","datePublished":"2023-11-15T05:00:00+00:00","dateModified":"2025-09-22T01:11:58+00:00","author":{"@id":"https:\/\/www.metacompliance.com\/es#\/schema\/person\/fe1b1dd873af281510fb0ad5f3fb5b38"},"breadcrumb":{"@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#primaryimage","url":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg","contentUrl":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/102406862-abc781ec-fa75-4ba8-b6eb-364a34a8f042.jpg","width":885,"height":560,"caption":"MetaCumplimiento"},{"@type":"BreadcrumbList","@id":"https:\/\/www.metacompliance.com\/es\/noticias\/la-expansion-de-metacompliance-en-dach-cobra-impulso-con-la-adquisicion-de-iys#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.metacompliance.com\/es"},{"@type":"ListItem","position":2,"name":"La expansi\u00f3n de MetaCompliance en DACH cobra impulso con la adquisici\u00f3n de IYS"}]},{"@type":"WebSite","@id":"https:\/\/www.metacompliance.com\/es#website","url":"https:\/\/www.metacompliance.com\/es","name":"MetaCompliance","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metacompliance.com\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.metacompliance.com\/es#\/schema\/person\/fe1b1dd873af281510fb0ad5f3fb5b38","name":"Rouge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g","caption":"Rouge"},"sameAs":["https:\/\/www.metacompliance.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/posts\/100276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/comments?post=100276"}],"version-history":[{"count":0,"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/posts\/100276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/media\/84649"}],"wp:attachment":[{"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/media?parent=100276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.metacompliance.com\/es\/wp-json\/wp\/v2\/categories?post=100276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}