{"id":106850,"date":"2014-09-25T09:05:00","date_gmt":"2014-09-25T08:05:00","guid":{"rendered":"https:\/\/metacomp.wpenginepowered.com\/non-classe\/metalearning-heralds"},"modified":"2025-09-22T02:17:47","modified_gmt":"2025-09-22T01:17:47","slug":"metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers","status":"publish","type":"post","link":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers","title":{"rendered":"MetaLearning annonce une nouvelle fa\u00e7on d&rsquo;augmenter les taux d&rsquo;adoption des contenus e-Learning parmi les employ\u00e9s et les tiers."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">MetaCompliance annonce le lancement de sa nouvelle plateforme d&rsquo;apprentissage mixte, MetaLearning. Ce nouveau produit est un environnement d&rsquo;apprentissage bas\u00e9 sur le cloud qui permet aux organisations de rassembler tous leurs contenus d&rsquo;apprentissage dans une plateforme solide pour l&rsquo;entreprise.<\/p>\n\n<p class=\"wp-block-paragraph\">MetaLearning est une plateforme technologique \u00e9volutive con\u00e7ue \u00e0 cet effet, qui vise \u00e0 devenir le mod\u00e8le industriel d&rsquo;un centre d&rsquo;apprentissage moderne, orient\u00e9 vers les m\u00e9dias sociaux, vers lequel les organisations dirigent leurs utilisateurs pour qu&rsquo;ils entreprennent tous les apprentissages.<\/p>\n\n<p class=\"wp-block-paragraph\">MetaLearning est ind\u00e9pendant du contenu d&rsquo;apprentissage. Le logiciel transmet \u00e0 l&rsquo;utilisateur des vid\u00e9os, des PowerPoint ou des contenus SCORM standard existants dans une interface moderne et intuitive. S&rsquo;inspirant de l&rsquo;aspect et de la convivialit\u00e9 des m\u00e9dias sociaux auxquels les utilisateurs sont habitu\u00e9s, MetaLearning cherche \u00e0 am\u00e9liorer l&rsquo;adoption de l&rsquo;apprentissage au sein de l&rsquo;organisation gr\u00e2ce \u00e0 l&rsquo;utilisation d&rsquo;une interface graphique riche et attrayante. En tant que plateforme orient\u00e9e entreprise, l&rsquo;utilisateur peut voir tout le contenu qui le concerne, qu&rsquo;il s&rsquo;agisse de sant\u00e9 et de s\u00e9curit\u00e9, de RH ou de conformit\u00e9. L&rsquo;utilisateur peut commenter les cours et communiquer le contenu au sein de l&rsquo;organisation interne. Ce dernier point constitue un excellent moyen de dispenser des cours au moment o\u00f9 les personnes ont besoin d&rsquo;apprendre.     <\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;objectif de MetaLearning est de fournir aux organisations un environnement technologique qui facilite l&rsquo;acc\u00e8s \u00e0 l&rsquo;apprentissage et fournit un r\u00e9f\u00e9rentiel permanent pour le cycle de vie de l&rsquo;apprentissage d&rsquo;un utilisateur au sein de l&rsquo;entreprise. MetaLearning permettra aux organisations d&rsquo;agr\u00e9ger le contenu r\u00e9sidant actuellement dans de multiples environnements LMS qui ont \u00e9t\u00e9 acquis au fil du temps. En d&rsquo;autres termes, MetaLearning centralise tout votre mat\u00e9riel de formation en un seul endroit. Le tout est accessible par une connexion unique bas\u00e9e sur le nom d&rsquo;utilisateur et le mot de passe de l&rsquo;utilisateur.<br\/>S&rsquo;exprimant sur le lancement de la nouvelle plateforme, Robert O&rsquo;Brien, PDG de MetaCompliance, a d\u00e9clar\u00e9 : \u00ab\u00a0Notre \u00e9quipe travaille sur MetaLearning depuis plus de deux ans ; il s&rsquo;agissait d&rsquo;une extension naturelle de notre gamme de produits et de produits existants tels que MyCompliance. Les clients doivent s&rsquo;assurer que leur personnel est correctement form\u00e9 et que les politiques cl\u00e9s sont respect\u00e9es. D&rsquo;o\u00f9 l&rsquo;association naturelle d&rsquo;une plateforme de gestion de l&rsquo;apprentissage et d&rsquo;un logiciel de gestion des politiques.   <\/p>\n\n<p class=\"wp-block-paragraph\">O&rsquo;Brien poursuit : \u00ab\u00a0MetaCompliance est une soci\u00e9t\u00e9 de d\u00e9veloppement de logiciels. Nous avons constat\u00e9 qu&rsquo;il existait une lacune sur le march\u00e9 en ce qui concerne une plate-forme LMS moderne et adapt\u00e9e \u00e0 l&rsquo;usage pr\u00e9vu, permettant d&rsquo;afficher non seulement SCORM, mais aussi tous les contenus dans une interface web moderne. Nous n&rsquo;avons pas trouv\u00e9 cette technologie et avons donc d\u00e9cid\u00e9 d&rsquo;en cr\u00e9er une \u00e0 partir de z\u00e9ro. MetaCompliance n&rsquo;a pas pour vocation de d\u00e9velopper des contenus d&rsquo;apprentissage, ce march\u00e9 \u00e9tant d\u00e9j\u00e0 desservi par d&rsquo;excellents fournisseurs de longue date, mais nous cherchons plut\u00f4t \u00e0 faire passer la technologie sous-jacente \u00e0 la prochaine g\u00e9n\u00e9ration tout en conservant la compatibilit\u00e9 avec les normes existantes.  <\/p>\n\n<p class=\"wp-block-paragraph\">MetaLearning sera d\u00e9voil\u00e9 aux clients de MetaCompliance lors de l&rsquo;\u00e9v\u00e9nement annuel qui se tiendra le 17 septembre 2013 \u00e0 l&rsquo;IOD de Pall Mall \u00e0 Londres.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00c0 propos de Metacompliance<\/p>\n\n<p class=\"wp-block-paragraph\">Metacompliance a pour objectif de faciliter la mise en conformit\u00e9 et la s\u00e9curit\u00e9 informatique des organisations. Le logiciel peut garantir la participation active de l&rsquo;ensemble du personnel aux initiatives de conformit\u00e9 telles que les politiques, l&rsquo;apprentissage en ligne et les enqu\u00eates, r\u00e9duisant ainsi le risque d&rsquo;incident de conformit\u00e9 et les amendes qui y sont associ\u00e9es. Le logiciel peut \u00eatre utilis\u00e9 pour d\u00e9montrer que le personnel comprend le contenu des politiques en \u00e9tant test\u00e9 \u00e0 l&rsquo;aide de questions. La participation accrue des utilisateurs aux campagnes de conformit\u00e9 et de s\u00e9curit\u00e9 informatique fournit les informations d&rsquo;audit n\u00e9cessaires pour g\u00e9n\u00e9rer des rapports qui permettent \u00e0 l&rsquo;organisation de d\u00e9montrer son \u00ab\u00a0devoir de diligence\u00a0\u00bb aux r\u00e9gulateurs.   <\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>2013 Metacompliance Limited. Tous droits r\u00e9serv\u00e9s. MetaCompliance et le logo MetaCompliance sont des marques d\u00e9pos\u00e9es de Metacompliance dans l&rsquo;Union europ\u00e9enne et dans d&rsquo;autres pays. Les autres marques et noms de produits sont des marques d\u00e9pos\u00e9es de leurs propri\u00e9taires respectifs.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>MetaCompliance annonce le lancement de sa nouvelle plateforme d&rsquo;apprentissage mixte, MetaLearning. Ce nouveau produit est un environnement d&rsquo;apprentissage bas\u00e9 sur le cloud qui permet aux organisations de rassembler tous leurs &hellip; <a href=\"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers\">Suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":18308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"footnotes":""},"categories":[177],"class_list":["post-106850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MetaLearning annonce une nouvelle fa\u00e7on d&#039;augmenter les taux d&#039;adoption des contenus e-Learning parmi les employ\u00e9s et les tiers. - MetaCompliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MetaLearning annonce une nouvelle fa\u00e7on d&#039;augmenter les taux d&#039;adoption des contenus e-Learning parmi les employ\u00e9s et les tiers. - MetaCompliance\" \/>\n<meta property=\"og:description\" content=\"MetaCompliance annonce le lancement de sa nouvelle plateforme d&rsquo;apprentissage mixte, MetaLearning. Ce nouveau produit est un environnement d&rsquo;apprentissage bas\u00e9 sur le cloud qui permet aux organisations de rassembler tous leurs &hellip; Suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers\" \/>\n<meta property=\"og:site_name\" content=\"MetaCompliance\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-25T08:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T01:17:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rouge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rouge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers\"},\"author\":{\"name\":\"Rouge\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr#\\\/schema\\\/person\\\/fe1b1dd873af281510fb0ad5f3fb5b38\"},\"headline\":\"MetaLearning annonce une nouvelle fa\u00e7on d&rsquo;augmenter les taux d&rsquo;adoption des contenus e-Learning parmi les employ\u00e9s et les tiers.\",\"datePublished\":\"2014-09-25T08:05:00+00:00\",\"dateModified\":\"2025-09-22T01:17:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers\"},\"wordCount\":771,\"image\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metacompliance.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg\",\"articleSection\":[\"Nouvelles de l'entreprise\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers\",\"url\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers\",\"name\":\"MetaLearning annonce une nouvelle fa\u00e7on d'augmenter les taux d'adoption des contenus e-Learning parmi les employ\u00e9s et les tiers. - MetaCompliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metacompliance.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg\",\"datePublished\":\"2014-09-25T08:05:00+00:00\",\"dateModified\":\"2025-09-22T01:17:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr#\\\/schema\\\/person\\\/fe1b1dd873af281510fb0ad5f3fb5b38\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#primaryimage\",\"url\":\"https:\\\/\\\/www.metacompliance.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.metacompliance.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"john schnobrich 2FPjlAyMQTA unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\\\/actualites\\\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MetaLearning annonce une nouvelle fa\u00e7on d&#8217;augmenter les taux d&#8217;adoption des contenus e-Learning parmi les employ\u00e9s et les tiers.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr#website\",\"url\":\"https:\\\/\\\/www.metacompliance.com\\\/fr\",\"name\":\"MetaCompliance\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metacompliance.com\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/fr#\\\/schema\\\/person\\\/fe1b1dd873af281510fb0ad5f3fb5b38\",\"name\":\"Rouge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g\",\"caption\":\"Rouge\"},\"sameAs\":[\"https:\\\/\\\/www.metacompliance.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MetaLearning annonce une nouvelle fa\u00e7on d'augmenter les taux d'adoption des contenus e-Learning parmi les employ\u00e9s et les tiers. - MetaCompliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers","og_locale":"fr_FR","og_type":"article","og_title":"MetaLearning annonce une nouvelle fa\u00e7on d'augmenter les taux d'adoption des contenus e-Learning parmi les employ\u00e9s et les tiers. - MetaCompliance","og_description":"MetaCompliance annonce le lancement de sa nouvelle plateforme d&rsquo;apprentissage mixte, MetaLearning. Ce nouveau produit est un environnement d&rsquo;apprentissage bas\u00e9 sur le cloud qui permet aux organisations de rassembler tous leurs &hellip; Suite","og_url":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers","og_site_name":"MetaCompliance","article_published_time":"2014-09-25T08:05:00+00:00","article_modified_time":"2025-09-22T01:17:47+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Rouge","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rouge","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#article","isPartOf":{"@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers"},"author":{"name":"Rouge","@id":"https:\/\/www.metacompliance.com\/fr#\/schema\/person\/fe1b1dd873af281510fb0ad5f3fb5b38"},"headline":"MetaLearning annonce une nouvelle fa\u00e7on d&rsquo;augmenter les taux d&rsquo;adoption des contenus e-Learning parmi les employ\u00e9s et les tiers.","datePublished":"2014-09-25T08:05:00+00:00","dateModified":"2025-09-22T01:17:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers"},"wordCount":771,"image":{"@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#primaryimage"},"thumbnailUrl":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg","articleSection":["Nouvelles de l'entreprise"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers","url":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers","name":"MetaLearning annonce une nouvelle fa\u00e7on d'augmenter les taux d'adoption des contenus e-Learning parmi les employ\u00e9s et les tiers. - MetaCompliance","isPartOf":{"@id":"https:\/\/www.metacompliance.com\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#primaryimage"},"image":{"@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#primaryimage"},"thumbnailUrl":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg","datePublished":"2014-09-25T08:05:00+00:00","dateModified":"2025-09-22T01:17:47+00:00","author":{"@id":"https:\/\/www.metacompliance.com\/fr#\/schema\/person\/fe1b1dd873af281510fb0ad5f3fb5b38"},"breadcrumb":{"@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#primaryimage","url":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg","contentUrl":"https:\/\/www.metacompliance.com\/wp-content\/uploads\/2025\/06\/john-schnobrich-2FPjlAyMQTA-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"john schnobrich 2FPjlAyMQTA unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/www.metacompliance.com\/fr\/actualites\/metalearning-annonce-une-nouvelle-facon-daugmenter-les-taux-dadoption-des-contenus-e-learning-parmi-les-employes-et-les-tiers#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.metacompliance.com\/fr"},{"@type":"ListItem","position":2,"name":"MetaLearning annonce une nouvelle fa\u00e7on d&#8217;augmenter les taux d&#8217;adoption des contenus e-Learning parmi les employ\u00e9s et les tiers."}]},{"@type":"WebSite","@id":"https:\/\/www.metacompliance.com\/fr#website","url":"https:\/\/www.metacompliance.com\/fr","name":"MetaCompliance","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metacompliance.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.metacompliance.com\/fr#\/schema\/person\/fe1b1dd873af281510fb0ad5f3fb5b38","name":"Rouge","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/979d60cad2f4c478c3d73fbd41f1d4f30ab6a193ea6f9e91917d90c552707d6a?s=96&d=mm&r=g","caption":"Rouge"},"sameAs":["https:\/\/www.metacompliance.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/posts\/106850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/comments?post=106850"}],"version-history":[{"count":0,"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/posts\/106850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/media\/18308"}],"wp:attachment":[{"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/media?parent=106850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.metacompliance.com\/fr\/wp-json\/wp\/v2\/categories?post=106850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}