{"id":110089,"date":"2025-09-25T13:21:38","date_gmt":"2025-09-25T12:21:38","guid":{"rendered":"https:\/\/www.metacompliance.com\/licensing-resources-and-documents"},"modified":"2026-05-12T15:18:03","modified_gmt":"2026-05-12T14:18:03","slug":"recursos-e-documentos-de-licenciamento","status":"publish","type":"page","link":"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento","title":{"rendered":"Recursos e documentos de licenciamento"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"footnotes":""},"class_list":["post-110089","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recursos e documentos de licenciamento - MetaCompliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recursos e documentos de licenciamento - MetaCompliance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento\" \/>\n<meta property=\"og:site_name\" content=\"MetaCompliance\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T14:18:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/pt\\\/recursos-e-documentos-de-licenciamento\",\"url\":\"https:\\\/\\\/www.metacompliance.com\\\/pt\\\/recursos-e-documentos-de-licenciamento\",\"name\":\"Recursos e documentos de licenciamento - MetaCompliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/pt#website\"},\"datePublished\":\"2025-09-25T12:21:38+00:00\",\"dateModified\":\"2026-05-12T14:18:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/pt\\\/recursos-e-documentos-de-licenciamento#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metacompliance.com\\\/pt\\\/recursos-e-documentos-de-licenciamento\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/pt\\\/recursos-e-documentos-de-licenciamento#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.metacompliance.com\\\/pt\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recursos e documentos de licenciamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metacompliance.com\\\/pt#website\",\"url\":\"https:\\\/\\\/www.metacompliance.com\\\/pt\",\"name\":\"MetaCompliance\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metacompliance.com\\\/pt?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recursos e documentos de licenciamento - MetaCompliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento","og_locale":"pt_PT","og_type":"article","og_title":"Recursos e documentos de licenciamento - MetaCompliance","og_url":"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento","og_site_name":"MetaCompliance","article_modified_time":"2026-05-12T14:18:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento","url":"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento","name":"Recursos e documentos de licenciamento - MetaCompliance","isPartOf":{"@id":"https:\/\/www.metacompliance.com\/pt#website"},"datePublished":"2025-09-25T12:21:38+00:00","dateModified":"2026-05-12T14:18:03+00:00","breadcrumb":{"@id":"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.metacompliance.com\/pt\/recursos-e-documentos-de-licenciamento#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.metacompliance.com\/pt"},{"@type":"ListItem","position":2,"name":"Recursos e documentos de licenciamento"}]},{"@type":"WebSite","@id":"https:\/\/www.metacompliance.com\/pt#website","url":"https:\/\/www.metacompliance.com\/pt","name":"MetaCompliance","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metacompliance.com\/pt?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www.metacompliance.com\/pt\/wp-json\/wp\/v2\/pages\/110089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metacompliance.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.metacompliance.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.metacompliance.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metacompliance.com\/pt\/wp-json\/wp\/v2\/comments?post=110089"}],"version-history":[{"count":0,"href":"https:\/\/www.metacompliance.com\/pt\/wp-json\/wp\/v2\/pages\/110089\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.metacompliance.com\/pt\/wp-json\/wp\/v2\/media?parent=110089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}